{"id":3201,"date":"2023-10-10T12:00:22","date_gmt":"2023-10-10T10:00:22","guid":{"rendered":"https:\/\/1a-retail.de\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/"},"modified":"2026-05-11T17:21:04","modified_gmt":"2026-05-11T15:21:04","slug":"time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro","status":"publish","type":"post","link":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/","title":{"rendered":"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3201\" class=\"elementor elementor-3201 elementor-1169\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b99bffc e-flex e-con-boxed e-con e-parent\" data-id=\"4b99bffc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42a4eb22 elementor-widget elementor-widget-text-editor\" data-id=\"42a4eb22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Com o Time Out Market Lisboa, surgiu em Lisboa um conceito que vai muito al\u00e9m de um mercado tradicional. No hist\u00f3rico Mercado da Ribeira, foi reinterpretado um espa\u00e7o onde a gastronomia, o compromisso com a qualidade e o conforto dos visitantes foram traduzidos num modelo economicamente s\u00f3lido. O mercado foi o primeiro Time Out Market de sempre e abriu em 2014. Hoje, conta com cerca de 26 restaurantes, 8 bares, cerca de uma d\u00fazia de lojas, uma \u00e1rea de eventos e uma escola de culin\u00e1ria.<\/p><p>No centro est\u00e1 a sele\u00e7\u00e3o criteriosa dos fornecedores. Ao contr\u00e1rio de muitos conceitos de food halls, a combina\u00e7\u00e3o de utiliza\u00e7\u00f5es n\u00e3o se baseia apenas no arrendamento, mas numa sele\u00e7\u00e3o orientada pela redac\u00e7\u00e3o. A pr\u00f3pria Time Out descreve o princ\u00edpio da seguinte forma: apenas as melhores ideias e conceitos da cidade, na opini\u00e3o da reda\u00e7\u00e3o, fazem parte do mercado. Desta forma, surge uma oferta com uma identidade clara, que se distingue significativamente das food courts cl\u00e1ssicas e confere ao local um perfil pr\u00f3prio.<\/p><p>Particularmente interessante \u00e9 a combina\u00e7\u00e3o entre a tradi\u00e7\u00e3o do mercado e a sua utiliza\u00e7\u00e3o contempor\u00e2nea. O Time Out Market est\u00e1 integrado num edif\u00edcio de mercado j\u00e1 existente, beneficiando assim de um enquadramento aut\u00eantico e historicamente consolidado. Ao mesmo tempo, este local foi desenvolvido de forma a criar um ponto de atra\u00e7\u00e3o com elevada aflu\u00eancia, visibilidade internacional e uma qualidade de perman\u00eancia palp\u00e1vel. O projeto demonstra assim de forma muito clara como um local de tradi\u00e7\u00e3o pode ser revitalizado atrav\u00e9s da escolha certa, de uma marca forte e de uma experi\u00eancia de visita claramente definida. O local atrai tanto os habitantes locais como os visitantes da cidade e, gra\u00e7as \u00e0 qualidade gastron\u00f3mica, constitui um motivo de visita por si s\u00f3. Assim, tornou-se vis\u00edvel desde cedo um modelo que hoje \u00e9 adotado em muitos locais: afastando-se da oferta puramente funcional, rumo a um local que se sustenta atrav\u00e9s da sele\u00e7\u00e3o, da atmosfera e da relev\u00e2ncia. Para al\u00e9m do pr\u00f3prio mercado, o impacto no entorno \u00e9 tamb\u00e9m not\u00e1vel.<\/p><p>A C\u00e2mara Municipal de Lisboa enquadra expressamente a renova\u00e7\u00e3o do Mercado da Ribeira numa valoriza\u00e7\u00e3o mais ampla da zona do Cais do Sodr\u00e9, associada a uma valoriza\u00e7\u00e3o da oferta gastron\u00f3mica na \u00e1rea circundante e a novos impulsos ao emprego. Ao mesmo tempo, estudos acad\u00e9micos descrevem o Cais do Sodr\u00e9 como um exemplo de transforma\u00e7\u00e3o urbana impulsionada pelo turismo. O Time Out Market n\u00e3o foi o \u00fanico catalisador, mas foi claramente um elemento vis\u00edvel deste desenvolvimento. Para n\u00f3s, por isso, o que \u00e9 decisivo n\u00e3o \u00e9 tanto o conceito de \u00abgentrifica\u00e7\u00e3o\u00bb, mas sim a constata\u00e7\u00e3o de que formatos de sucesso nas \u00e1reas da gastronomia e do lazer t\u00eam frequentemente um impacto que vai muito al\u00e9m do pr\u00f3prio im\u00f3vel e podem redefinir bairros inteiros \u2013 de forma positiva, mas tamb\u00e9m com as tens\u00f5es conhecidas que uma forte dinamiza\u00e7\u00e3o tur\u00edstica acarreta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Com o Time Out Market Lisboa, surgiu em Lisboa um conceito que vai muito al\u00e9m de um mercado tradicional. No hist\u00f3rico Mercado da Ribeira, foi reinterpretado um espa\u00e7o onde a gastronomia, o compromisso com a qualidade e o conforto dos visitantes foram traduzidos num modelo economicamente s\u00f3lido. O mercado foi o primeiro Time Out Market [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3200,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-3201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro - 1A Retail<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro - 1A Retail\" \/>\n<meta property=\"og:description\" content=\"Com o Time Out Market Lisboa, surgiu em Lisboa um conceito que vai muito al\u00e9m de um mercado tradicional. No hist\u00f3rico Mercado da Ribeira, foi reinterpretado um espa\u00e7o onde a gastronomia, o compromisso com a qualidade e o conforto dos visitantes foram traduzidos num modelo economicamente s\u00f3lido. O mercado foi o primeiro Time Out Market [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/\" \/>\n<meta property=\"og:site_name\" content=\"1A Retail\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T10:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T15:21:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/1a-retail.de\/wp-content\/uploads\/2023\/10\/1AR_beitrag_lissabon_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1521\" \/>\n\t<meta property=\"og:image:height\" content=\"1140\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"motointermedia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"motointermedia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/\"},\"author\":{\"name\":\"motointermedia\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#\\\/schema\\\/person\\\/ea6c3fab174f04e65f5e51afe94b4760\"},\"headline\":\"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro\",\"datePublished\":\"2023-10-10T10:00:22+00:00\",\"dateModified\":\"2026-05-11T15:21:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/\"},\"wordCount\":539,\"publisher\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1a-retail.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/1AR_beitrag_lissabon_02.jpg\",\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/\",\"url\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/\",\"name\":\"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro - 1A Retail\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1a-retail.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/1AR_beitrag_lissabon_02.jpg\",\"datePublished\":\"2023-10-10T10:00:22+00:00\",\"dateModified\":\"2026-05-11T15:21:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/1a-retail.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/1AR_beitrag_lissabon_02.jpg\",\"contentUrl\":\"https:\\\/\\\/1a-retail.de\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/1AR_beitrag_lissabon_02.jpg\",\"width\":1521,\"height\":1140},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/2023\\\/10\\\/10\\\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#website\",\"url\":\"https:\\\/\\\/1a-retail.de\\\/\",\"name\":\"1A Retail\",\"description\":\"Innovative L\u00f6sungen im Retail-Bereich\",\"publisher\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/1a-retail.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#organization\",\"name\":\"1A Retail\",\"url\":\"https:\\\/\\\/1a-retail.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/1a-retail.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1A-RETAIL_2026.jpg\",\"contentUrl\":\"https:\\\/\\\/1a-retail.de\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1A-RETAIL_2026.jpg\",\"width\":350,\"height\":100,\"caption\":\"1A Retail\"},\"image\":{\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/1a-retail.de\\\/#\\\/schema\\\/person\\\/ea6c3fab174f04e65f5e51afe94b4760\",\"name\":\"motointermedia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab2ed830f22d68f77979a9779ddd786fbad630717729890a0b4333e08093eb08?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab2ed830f22d68f77979a9779ddd786fbad630717729890a0b4333e08093eb08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ab2ed830f22d68f77979a9779ddd786fbad630717729890a0b4333e08093eb08?s=96&d=mm&r=g\",\"caption\":\"motointermedia\"},\"sameAs\":[\"https:\\\/\\\/dev.1a-retail.de\"],\"url\":\"https:\\\/\\\/1a-retail.de\\\/pt-pt\\\/author\\\/motointermedia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro - 1A Retail","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/","og_locale":"pt_PT","og_type":"article","og_title":"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro - 1A Retail","og_description":"Com o Time Out Market Lisboa, surgiu em Lisboa um conceito que vai muito al\u00e9m de um mercado tradicional. No hist\u00f3rico Mercado da Ribeira, foi reinterpretado um espa\u00e7o onde a gastronomia, o compromisso com a qualidade e o conforto dos visitantes foram traduzidos num modelo economicamente s\u00f3lido. O mercado foi o primeiro Time Out Market [&hellip;]","og_url":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/","og_site_name":"1A Retail","article_published_time":"2023-10-10T10:00:22+00:00","article_modified_time":"2026-05-11T15:21:04+00:00","og_image":[{"width":1521,"height":1140,"url":"https:\/\/1a-retail.de\/wp-content\/uploads\/2023\/10\/1AR_beitrag_lissabon_02.jpg","type":"image\/jpeg"}],"author":"motointermedia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"motointermedia","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/#article","isPartOf":{"@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/"},"author":{"name":"motointermedia","@id":"https:\/\/1a-retail.de\/#\/schema\/person\/ea6c3fab174f04e65f5e51afe94b4760"},"headline":"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro","datePublished":"2023-10-10T10:00:22+00:00","dateModified":"2026-05-11T15:21:04+00:00","mainEntityOfPage":{"@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/"},"wordCount":539,"publisher":{"@id":"https:\/\/1a-retail.de\/#organization"},"image":{"@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/#primaryimage"},"thumbnailUrl":"https:\/\/1a-retail.de\/wp-content\/uploads\/2023\/10\/1AR_beitrag_lissabon_02.jpg","inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/","url":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/","name":"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro - 1A Retail","isPartOf":{"@id":"https:\/\/1a-retail.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/#primaryimage"},"image":{"@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/#primaryimage"},"thumbnailUrl":"https:\/\/1a-retail.de\/wp-content\/uploads\/2023\/10\/1AR_beitrag_lissabon_02.jpg","datePublished":"2023-10-10T10:00:22+00:00","dateModified":"2026-05-11T15:21:04+00:00","breadcrumb":{"@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/#primaryimage","url":"https:\/\/1a-retail.de\/wp-content\/uploads\/2023\/10\/1AR_beitrag_lissabon_02.jpg","contentUrl":"https:\/\/1a-retail.de\/wp-content\/uploads\/2023\/10\/1AR_beitrag_lissabon_02.jpg","width":1521,"height":1140},{"@type":"BreadcrumbList","@id":"https:\/\/1a-retail.de\/pt-pt\/2023\/10\/10\/time-out-market-lisboa-um-polo-de-atracao-turistica-que-transformou-todo-o-bairro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/1a-retail.de\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Time Out Market Lisboa \u2013 um polo de atra\u00e7\u00e3o tur\u00edstica que transformou todo o bairro"}]},{"@type":"WebSite","@id":"https:\/\/1a-retail.de\/#website","url":"https:\/\/1a-retail.de\/","name":"1A Retail","description":"Innovative L\u00f6sungen im Retail-Bereich","publisher":{"@id":"https:\/\/1a-retail.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/1a-retail.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/1a-retail.de\/#organization","name":"1A Retail","url":"https:\/\/1a-retail.de\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/1a-retail.de\/#\/schema\/logo\/image\/","url":"https:\/\/1a-retail.de\/wp-content\/uploads\/2024\/10\/1A-RETAIL_2026.jpg","contentUrl":"https:\/\/1a-retail.de\/wp-content\/uploads\/2024\/10\/1A-RETAIL_2026.jpg","width":350,"height":100,"caption":"1A Retail"},"image":{"@id":"https:\/\/1a-retail.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/1a-retail.de\/#\/schema\/person\/ea6c3fab174f04e65f5e51afe94b4760","name":"motointermedia","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/ab2ed830f22d68f77979a9779ddd786fbad630717729890a0b4333e08093eb08?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ab2ed830f22d68f77979a9779ddd786fbad630717729890a0b4333e08093eb08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab2ed830f22d68f77979a9779ddd786fbad630717729890a0b4333e08093eb08?s=96&d=mm&r=g","caption":"motointermedia"},"sameAs":["https:\/\/dev.1a-retail.de"],"url":"https:\/\/1a-retail.de\/pt-pt\/author\/motointermedia\/"}]}},"_links":{"self":[{"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/posts\/3201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/comments?post=3201"}],"version-history":[{"count":4,"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/posts\/3201\/revisions"}],"predecessor-version":[{"id":3205,"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/posts\/3201\/revisions\/3205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/media\/3200"}],"wp:attachment":[{"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/media?parent=3201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/categories?post=3201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/1a-retail.de\/pt-pt\/wp-json\/wp\/v2\/tags?post=3201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}